{"id":1875,"date":"2026-07-14T22:53:52","date_gmt":"2026-07-14T20:53:52","guid":{"rendered":"https:\/\/senneriffa.de\/?p=1875"},"modified":"2026-07-14T22:54:41","modified_gmt":"2026-07-14T20:54:41","slug":"landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026","status":"publish","type":"post","link":"https:\/\/senneriffa.de\/en\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/","title":{"rendered":"(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der  FSG Bielefeld  2026"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/senneriffa.de\/de\/wp-json\/wp\/v2\/posts\/1875\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Deutsch.<\/p>\n","protected":false},"author":1,"featured_media":1872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-1875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026 - FSG Bielefeld e. V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026 - FSG Bielefeld e. V.\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Deutsch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"FSG Bielefeld e. V.\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T20:53:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T20:54:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1728\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminmanuel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminmanuel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/\"},\"author\":{\"name\":\"adminmanuel\",\"@id\":\"https:\/\/senneriffa.de\/#\/schema\/person\/4b70f98b050a1707ee843be5af1e77d3\"},\"headline\":\"(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026\",\"datePublished\":\"2026-07-14T20:53:52+00:00\",\"dateModified\":\"2026-07-14T20:54:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/\"},\"wordCount\":199,\"image\":{\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/\",\"url\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/\",\"name\":\"(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026 - FSG Bielefeld e. V.\",\"isPartOf\":{\"@id\":\"https:\/\/senneriffa.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg\",\"datePublished\":\"2026-07-14T20:53:52+00:00\",\"dateModified\":\"2026-07-14T20:54:41+00:00\",\"author\":{\"@id\":\"https:\/\/senneriffa.de\/#\/schema\/person\/4b70f98b050a1707ee843be5af1e77d3\"},\"breadcrumb\":{\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#primaryimage\",\"url\":\"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg\",\"contentUrl\":\"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg\",\"width\":1728,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/senneriffa.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/senneriffa.de\/#website\",\"url\":\"https:\/\/senneriffa.de\/\",\"name\":\"FSG Bielefeld e. V.\",\"description\":\"Familien-Sport-Gemeinschaft\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/senneriffa.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/senneriffa.de\/#\/schema\/person\/4b70f98b050a1707ee843be5af1e77d3\",\"name\":\"adminmanuel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/99abf7036ef2667faa07e0fee60d111435845b13747388c96fee19453f550554?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/99abf7036ef2667faa07e0fee60d111435845b13747388c96fee19453f550554?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/99abf7036ef2667faa07e0fee60d111435845b13747388c96fee19453f550554?s=96&d=mm&r=g\",\"caption\":\"adminmanuel\"},\"url\":\"https:\/\/senneriffa.de\/en\/author\/adminmanuel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026 - FSG Bielefeld e. V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/","og_locale":"en_US","og_type":"article","og_title":"(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026 - FSG Bielefeld e. V.","og_description":"Sorry, this entry is only available in Deutsch.","og_url":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/","og_site_name":"FSG Bielefeld e. V.","article_published_time":"2026-07-14T20:53:52+00:00","article_modified_time":"2026-07-14T20:54:41+00:00","og_image":[{"width":1728,"height":1152,"url":"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg","type":"image\/jpeg"}],"author":"adminmanuel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adminmanuel","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#article","isPartOf":{"@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/"},"author":{"name":"adminmanuel","@id":"https:\/\/senneriffa.de\/#\/schema\/person\/4b70f98b050a1707ee843be5af1e77d3"},"headline":"(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026","datePublished":"2026-07-14T20:53:52+00:00","dateModified":"2026-07-14T20:54:41+00:00","mainEntityOfPage":{"@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/"},"wordCount":199,"image":{"@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/","url":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/","name":"(Deutsch) Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026 - FSG Bielefeld e. V.","isPartOf":{"@id":"https:\/\/senneriffa.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#primaryimage"},"image":{"@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg","datePublished":"2026-07-14T20:53:52+00:00","dateModified":"2026-07-14T20:54:41+00:00","author":{"@id":"https:\/\/senneriffa.de\/#\/schema\/person\/4b70f98b050a1707ee843be5af1e77d3"},"breadcrumb":{"@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#primaryimage","url":"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg","contentUrl":"https:\/\/senneriffa.de\/wp-content\/uploads\/2026\/07\/bogenschiessen-01-web.jpeg","width":1728,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/senneriffa.de\/landesmeisterschaft-im-bogenschiessen-bei-der-fsg-bielefeld-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/senneriffa.de\/"},{"@type":"ListItem","position":2,"name":"Landesmeisterschaft im Bogenschie\u00dfen bei der FSG Bielefeld 2026"}]},{"@type":"WebSite","@id":"https:\/\/senneriffa.de\/#website","url":"https:\/\/senneriffa.de\/","name":"FSG Bielefeld e. V.","description":"Familien-Sport-Gemeinschaft","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/senneriffa.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/senneriffa.de\/#\/schema\/person\/4b70f98b050a1707ee843be5af1e77d3","name":"adminmanuel","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/99abf7036ef2667faa07e0fee60d111435845b13747388c96fee19453f550554?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99abf7036ef2667faa07e0fee60d111435845b13747388c96fee19453f550554?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99abf7036ef2667faa07e0fee60d111435845b13747388c96fee19453f550554?s=96&d=mm&r=g","caption":"adminmanuel"},"url":"https:\/\/senneriffa.de\/en\/author\/adminmanuel\/"}]}},"_links":{"self":[{"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/posts\/1875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/comments?post=1875"}],"version-history":[{"count":2,"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/posts\/1875\/revisions"}],"predecessor-version":[{"id":1877,"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/posts\/1875\/revisions\/1877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/media\/1872"}],"wp:attachment":[{"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/media?parent=1875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/categories?post=1875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/senneriffa.de\/en\/wp-json\/wp\/v2\/tags?post=1875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}